{"id":33,"count":7,"description":"","link":"https:\/\/lnbz.la\/blog\/category\/car-loan\/","name":"Car Loan","slug":"car-loan","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Car Loan Archives - LoanBuzz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lnbz.la\/blog\/category\/car-loan\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Car Loan Archives - LoanBuzz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lnbz.la\/blog\/category\/car-loan\/\" \/>\n<meta property=\"og:site_name\" content=\"LoanBuzz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/lnbz.la\\\/blog\\\/category\\\/car-loan\\\/\",\"url\":\"https:\\\/\\\/lnbz.la\\\/blog\\\/category\\\/car-loan\\\/\",\"name\":\"Car Loan Archives - LoanBuzz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lnbz.la\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lnbz.la\\\/blog\\\/category\\\/car-loan\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lnbz.la\\\/blog\\\/category\\\/car-loan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lnbz.la\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Car Loan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lnbz.la\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/lnbz.la\\\/blog\\\/\",\"name\":\"LoanBuzz\",\"description\":\"Review of Mortgage, Car Loan, Personal Loan, Business Loan topics\",\"publisher\":{\"@id\":\"https:\\\/\\\/lnbz.la\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lnbz.la\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lnbz.la\\\/blog\\\/#organization\",\"name\":\"LoanBuzz\",\"url\":\"https:\\\/\\\/lnbz.la\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lnbz.la\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lnbz.la\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/mynewlogos.png\",\"contentUrl\":\"https:\\\/\\\/lnbz.la\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/mynewlogos.png\",\"width\":272,\"height\":64,\"caption\":\"LoanBuzz\"},\"image\":{\"@id\":\"https:\\\/\\\/lnbz.la\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Car Loan Archives - LoanBuzz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lnbz.la\/blog\/category\/car-loan\/","og_locale":"en_US","og_type":"article","og_title":"Car Loan Archives - LoanBuzz","og_url":"https:\/\/lnbz.la\/blog\/category\/car-loan\/","og_site_name":"LoanBuzz","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/lnbz.la\/blog\/category\/car-loan\/","url":"https:\/\/lnbz.la\/blog\/category\/car-loan\/","name":"Car Loan Archives - LoanBuzz","isPartOf":{"@id":"https:\/\/lnbz.la\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/lnbz.la\/blog\/category\/car-loan\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/lnbz.la\/blog\/category\/car-loan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lnbz.la\/blog\/"},{"@type":"ListItem","position":2,"name":"Car Loan"}]},{"@type":"WebSite","@id":"https:\/\/lnbz.la\/blog\/#website","url":"https:\/\/lnbz.la\/blog\/","name":"LoanBuzz","description":"Review of Mortgage, Car Loan, Personal Loan, Business Loan topics","publisher":{"@id":"https:\/\/lnbz.la\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lnbz.la\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lnbz.la\/blog\/#organization","name":"LoanBuzz","url":"https:\/\/lnbz.la\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lnbz.la\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/lnbz.la\/blog\/wp-content\/uploads\/2024\/03\/mynewlogos.png","contentUrl":"https:\/\/lnbz.la\/blog\/wp-content\/uploads\/2024\/03\/mynewlogos.png","width":272,"height":64,"caption":"LoanBuzz"},"image":{"@id":"https:\/\/lnbz.la\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lnbz.la\/blog\/wp-json\/wp\/v2\/categories\/33","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lnbz.la\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/lnbz.la\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/lnbz.la\/blog\/wp-json\/wp\/v2\/posts?categories=33"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}